{"id":2647,"date":"2020-06-04T17:06:47","date_gmt":"2020-06-04T16:06:47","guid":{"rendered":"https:\/\/seed4.me\/blog\/wp-content\/uploads\/2020\/06\/conflict-resolution.jpg"},"modified":"2020-06-04T17:06:47","modified_gmt":"2020-06-04T16:06:47","slug":"conflict-resolution","status":"inherit","type":"attachment","link":"https:\/\/www.getpremium.vip\/blog\/apps-know-to-have-conflict-with-vpn\/conflict-resolution\/","title":{"rendered":"conflict-resolution"},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a class=\"thumbnail\" href='https:\/\/www.getpremium.vip\/blog\/wp-content\/uploads\/2020\/06\/conflict-resolution.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"126\" src=\"https:\/\/www.getpremium.vip\/blog\/wp-content\/uploads\/2020\/06\/conflict-resolution-300x126.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.getpremium.vip\/blog\/wp-content\/uploads\/2020\/06\/conflict-resolution-300x126.jpg 300w, https:\/\/www.getpremium.vip\/blog\/wp-content\/uploads\/2020\/06\/conflict-resolution-768x323.jpg 768w, https:\/\/www.getpremium.vip\/blog\/wp-content\/uploads\/2020\/06\/conflict-resolution-1024x430.jpg 1024w, https:\/\/www.getpremium.vip\/blog\/wp-content\/uploads\/2020\/06\/conflict-resolution-357x150.jpg 357w, https:\/\/www.getpremium.vip\/blog\/wp-content\/uploads\/2020\/06\/conflict-resolution.jpg 1400w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1400,"height":588,"file":"2020\/06\/conflict-resolution.jpg","sizes":{"thumbnail":{"file":"conflict-resolution-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.getpremium.vip\/blog\/wp-content\/uploads\/2020\/06\/conflict-resolution-150x150.jpg"},"medium":{"file":"conflict-resolution-300x126.jpg","width":300,"height":126,"mime_type":"image\/jpeg","source_url":"https:\/\/www.getpremium.vip\/blog\/wp-content\/uploads\/2020\/06\/conflict-resolution-300x126.jpg"},"medium_large":{"file":"conflict-resolution-768x323.jpg","width":768,"height":323,"mime_type":"image\/jpeg","source_url":"https:\/\/www.getpremium.vip\/blog\/wp-content\/uploads\/2020\/06\/conflict-resolution-768x323.jpg"},"large":{"file":"conflict-resolution-1024x430.jpg","width":1024,"height":430,"mime_type":"image\/jpeg","source_url":"https:\/\/www.getpremium.vip\/blog\/wp-content\/uploads\/2020\/06\/conflict-resolution-1024x430.jpg"},"wpbs-featured":{"file":"conflict-resolution-638x300.jpg","width":638,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.getpremium.vip\/blog\/wp-content\/uploads\/2020\/06\/conflict-resolution-638x300.jpg"},"wpbs-featured-home":{"file":"conflict-resolution-970x311.jpg","width":970,"height":311,"mime_type":"image\/jpeg","source_url":"https:\/\/www.getpremium.vip\/blog\/wp-content\/uploads\/2020\/06\/conflict-resolution-970x311.jpg"},"wpbs-featured-carousel":{"file":"conflict-resolution-970x400.jpg","width":970,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.getpremium.vip\/blog\/wp-content\/uploads\/2020\/06\/conflict-resolution-970x400.jpg"},"bones-thumb-600":{"file":"conflict-resolution-357x150.jpg","width":357,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.getpremium.vip\/blog\/wp-content\/uploads\/2020\/06\/conflict-resolution-357x150.jpg"},"bones-thumb-300":{"file":"conflict-resolution-300x100.jpg","width":300,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.getpremium.vip\/blog\/wp-content\/uploads\/2020\/06\/conflict-resolution-300x100.jpg"},"post-thumbnail":{"file":"conflict-resolution-125x125.jpg","width":125,"height":125,"mime_type":"image\/jpeg","source_url":"https:\/\/www.getpremium.vip\/blog\/wp-content\/uploads\/2020\/06\/conflict-resolution-125x125.jpg"},"full":{"file":"conflict-resolution.jpg","width":1400,"height":588,"mime_type":"image\/jpeg","source_url":"https:\/\/www.getpremium.vip\/blog\/wp-content\/uploads\/2020\/06\/conflict-resolution.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":2640,"source_url":"https:\/\/www.getpremium.vip\/blog\/wp-content\/uploads\/2020\/06\/conflict-resolution.jpg","_links":{"self":[{"href":"https:\/\/www.getpremium.vip\/blog\/wp-json\/wp\/v2\/media\/2647"}],"collection":[{"href":"https:\/\/www.getpremium.vip\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.getpremium.vip\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.getpremium.vip\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.getpremium.vip\/blog\/wp-json\/wp\/v2\/comments?post=2647"}]}}